{"id":5774,"count":2,"description":"","link":"https:\/\/vilagrasa.com\/fr\/disenadores\/pascual-salvador-fr\/","name":"Pascual Salvador","slug":"pascual-salvador-fr","taxonomy":"disenadores","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dise\u00f1os de Pascual Salvador para Vilagrasa<\/title>\n<meta name=\"description\" content=\"Estas son algunas de los creaciones de Pascual Salvador para Vilagrasa. Un dise\u00f1o \u00fanico y original en un producto funcional que adem\u00e1s a\u00f1ade distinci\u00f3n a su entorno.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vilagrasa.com\/fr\/disenadores\/pascual-salvador-fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dise\u00f1os de Pascual Salvador para Vilagrasa\" \/>\n<meta property=\"og:description\" content=\"Estas son algunas de los creaciones de Pascual Salvador para Vilagrasa. Un dise\u00f1o \u00fanico y original en un producto funcional que adem\u00e1s a\u00f1ade distinci\u00f3n a su entorno.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vilagrasa.com\/fr\/disenadores\/pascual-salvador-fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Vilagrasa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/vilagrasa.com\\\/fr\\\/disenadores\\\/pascual-salvador-fr\\\/\",\"url\":\"https:\\\/\\\/vilagrasa.com\\\/fr\\\/disenadores\\\/pascual-salvador-fr\\\/\",\"name\":\"Dise\u00f1os de Pascual Salvador para Vilagrasa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vilagrasa.com\\\/fr\\\/#website\"},\"description\":\"Estas son algunas de los creaciones de Pascual Salvador para Vilagrasa. Un dise\u00f1o \u00fanico y original en un producto funcional que adem\u00e1s a\u00f1ade distinci\u00f3n a su entorno.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vilagrasa.com\\\/fr\\\/disenadores\\\/pascual-salvador-fr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vilagrasa.com\\\/fr\\\/disenadores\\\/pascual-salvador-fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/vilagrasa.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pascual Salvador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vilagrasa.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/vilagrasa.com\\\/fr\\\/\",\"name\":\"Vilagrasa\",\"description\":\"Fabricante de mobiliario urbano - Papeleras de dise\u00f1o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vilagrasa.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dise\u00f1os de Pascual Salvador para Vilagrasa","description":"Estas son algunas de los creaciones de Pascual Salvador para Vilagrasa. Un dise\u00f1o \u00fanico y original en un producto funcional que adem\u00e1s a\u00f1ade distinci\u00f3n a su entorno.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vilagrasa.com\/fr\/disenadores\/pascual-salvador-fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Dise\u00f1os de Pascual Salvador para Vilagrasa","og_description":"Estas son algunas de los creaciones de Pascual Salvador para Vilagrasa. Un dise\u00f1o \u00fanico y original en un producto funcional que adem\u00e1s a\u00f1ade distinci\u00f3n a su entorno.","og_url":"https:\/\/vilagrasa.com\/fr\/disenadores\/pascual-salvador-fr\/","og_site_name":"Vilagrasa","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/vilagrasa.com\/fr\/disenadores\/pascual-salvador-fr\/","url":"https:\/\/vilagrasa.com\/fr\/disenadores\/pascual-salvador-fr\/","name":"Dise\u00f1os de Pascual Salvador para Vilagrasa","isPartOf":{"@id":"https:\/\/vilagrasa.com\/fr\/#website"},"description":"Estas son algunas de los creaciones de Pascual Salvador para Vilagrasa. Un dise\u00f1o \u00fanico y original en un producto funcional que adem\u00e1s a\u00f1ade distinci\u00f3n a su entorno.","breadcrumb":{"@id":"https:\/\/vilagrasa.com\/fr\/disenadores\/pascual-salvador-fr\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/vilagrasa.com\/fr\/disenadores\/pascual-salvador-fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/vilagrasa.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Pascual Salvador"}]},{"@type":"WebSite","@id":"https:\/\/vilagrasa.com\/fr\/#website","url":"https:\/\/vilagrasa.com\/fr\/","name":"Vilagrasa","description":"Fabricante de mobiliario urbano - Papeleras de dise\u00f1o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vilagrasa.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/vilagrasa.com\/fr\/wp-json\/wp\/v2\/disenadores\/5774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vilagrasa.com\/fr\/wp-json\/wp\/v2\/disenadores"}],"about":[{"href":"https:\/\/vilagrasa.com\/fr\/wp-json\/wp\/v2\/taxonomies\/disenadores"}],"wp:post_type":[{"href":"https:\/\/vilagrasa.com\/fr\/wp-json\/wp\/v2\/productos?disenadores=5774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}